{"id":19235,"date":"2020-04-04T10:53:44","date_gmt":"2020-04-04T08:53:44","guid":{"rendered":"https:\/\/sajec.de\/blog\/?p=19235"},"modified":"2020-04-04T10:53:44","modified_gmt":"2020-04-04T08:53:44","slug":"das-kindle","status":"publish","type":"post","link":"https:\/\/sajec.de\/blog\/das-kindle\/","title":{"rendered":"Das KINDLE"},"content":{"rendered":"\n<p style=\"color:#442272\" class=\"has-text-color has-background has-normal-font-size has-light-gray-background-color wp-block-paragraph\">&#8230; bed\u00fcrfte dringend einiger Aufr\u00e4umarbeiten. Mittlerweile tummeln sich da genau 1493 Dokumente, davon gesch\u00e4tzt mittlerweile sicher 70 % f\u00fcr QAF, der Rest f\u00fcr J\u00b2AU + ein kleines bisschen supernatural. <br>Und ich wollte auch Aufr\u00e4umen &#8230;. aber wie das immer so ist; dann habe ich doch auf den \u00fcblichen Dealer-Wiesen nach neuen stories gesucht (<em>nur mal schnell gucken<\/em>); und fix 6 neue gefunden, zubereitet und draufgeschubst, und nun habe ich keine Zeit mehr zum Sortieren. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; bed\u00fcrfte dringend einiger Aufr\u00e4umarbeiten. Mittlerweile tummeln sich da genau 1493 Dokumente, davon gesch\u00e4tzt mittlerweile sicher 70 % f\u00fcr QAF, der Rest f\u00fcr J\u00b2AU + ein kleines bisschen supernatural. Und ich wollte auch Aufr\u00e4umen &#8230;. aber wie das immer so &hellip; <a href=\"https:\/\/sajec.de\/blog\/das-kindle\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19235","post","type-post","status-publish","format-standard","hentry","category-tagebuch"],"_links":{"self":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/comments?post=19235"}],"version-history":[{"count":2,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19235\/revisions"}],"predecessor-version":[{"id":19237,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19235\/revisions\/19237"}],"wp:attachment":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/media?parent=19235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/categories?post=19235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/tags?post=19235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}