{"id":19281,"date":"2020-05-23T12:11:50","date_gmt":"2020-05-23T10:11:50","guid":{"rendered":"https:\/\/sajec.de\/blog\/?p=19281"},"modified":"2020-05-23T12:27:43","modified_gmt":"2020-05-23T10:27:43","slug":"die-erhabenheit-eines-funktionierenden-spuelkastens","status":"publish","type":"post","link":"https:\/\/sajec.de\/blog\/die-erhabenheit-eines-funktionierenden-spuelkastens\/","title":{"rendered":"Die Erhabenheit eines funktionierenden Sp\u00fclkastens"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">oder wie schnell man in Schablonen ger\u00e4t. Aber eigentlich ist es einfach so, dass mir gerade langweilig ist. Deswegen kommt selbst ein Blogeintrag \u00fcber den nach 8 Jahren Undicht-Seins ausgetauschten Sp\u00fclkasten gerade gelegen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Sp\u00fclkasten ist also seit dem legend\u00e4ren Vancouver-Trip-Jahr kaputt, genauer das Dingens, das den Wasserzufluss beendet, wenn der Kasten voll ist, funktionierte nicht mehr. Und damit nicht Niagarafall-artig Wasser sinnlos direkt ins Klo pl\u00e4tschert, drehten wir eben seitdem immer direkt am Ventil auf und nach dem Sp\u00fclen zu. Das bedeutete, dass man auch immer so lange sitzen musste, bis gen\u00fcgend Wasser zum Sp\u00fclen im Kasten nachgelaufen war, wenn der Vorg\u00e4nger nicht geduldig genug war, das Nachf\u00fcllen abzuwarten, um danach erst zuzudrehen. Wann immer ich also auf dem heimischen WC hockte, folgte automatisch der verrenkte Griff nach hinten, um das Ventil aufzudrehen, was nach Jahren de facto in meine Gene mit hineinprogrammiert worden ist. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bis das Ventil &#8211; nie dazu auserkoren, jahrelang t\u00e4glich hin- und hergedreht zu werden &#8211; schlicht sich \u00fcberdrehte und zum Schluss ganz aufgab. Nat\u00fcrlich am Feiertag (Himmelfahrt), nat\u00fcrlich nachts um 22 Uhr, nat\u00fcrlich in der Stellung &#8222;Wasser Marsch&#8220;; was nicht nur laut ist, sondern auch eine Verschwendung sondergleichen! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Also musste Knuffel 3 Stockwerke + 1 Kellergeschoss runter , das Wasser abdrehen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nacht war schrecklich; ich hatte das Gef\u00fchl, alle 20 Minuten auf Toilette zu m\u00fcssen, aber nicht zu d\u00fcrfen, was das Bed\u00fcrfnis nur noch vergr\u00f6\u00dferte. Ich war unruhig, schlief wenn \u00fcberhaupt nur minutenweise; bescheuerter Weise auch von der Angst getrieben, dass Knuffel den falschen Wasserhahn des n\u00e4chtens eventuell abgedreht haben k\u00f6nnte, und uns am Morgen ein w\u00fctender Nachbarmob mit Forken und Gie\u00dfkannen aus dem Bett br\u00fcllen w\u00fcrde.<br>Oder wie wir das in den kommenden Tagen praktizieren sollen, wenn warum auch immer keine Reparatur innerhalb der n\u00e4chsten Stunden m\u00f6glich sein w\u00fcrde! Vor jedem Klogang 4 Etagen in den Keller und wieder zur\u00fcck? Ich schaff es ja manchmal gerade so die paar Meter von Schlafzimmer ins Bad! Kein Geschirrsp\u00fcler, keine Waschmaschine; und selbst das Z\u00e4hneputzen w\u00fcrden strategisches Vordenken erfordern.<br>Man merkt erst, was man f\u00fcr Annehmlichkeiten hat, wenn man sie nicht mehr hat. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morgens dann den Wohnungshauptwasserhahn eben fix wieder \u00f6ffnen &#8211;> Knuffel musste wieder alle 6 Treppenstiegen runter, w\u00e4hrend ich alle verf\u00fcgbaren Beh\u00e4ltnisse und insbesondere die Kaffeemaschine mit dem kostbaren Nass best\u00fcckte, bevor Knuffel am Wasserhahn harrend den Befehl zum erneuten Abdrehen bekam. <br><br>Und dann hie\u00df es Warten auf <s>dem<\/s> den Klempner! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der kam dann auch \u00fcberraschend nach einer Stunde, hatte sogar ein neues Ventil und einen neuen Schwimmer (so hei\u00dft korrekter Weise das Ding von vorhin) dabei, aber das Wasser lief nach Austausch immer noch minimal durch. Ich h\u00e4tte damit leben k\u00f6nnen; ich w\u00fcrde eben wie vorher auch am neuen Ventil wieder Wasser auf- und zudrehen. Aber offenbar war das nun eine Frage der Klempner-Ehre! Es kann nur einen geben &#8211; und das ist ein tadellos funktionierender Sp\u00fclkasten! Den er dann auch noch neu holte und anmontierte. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und nun muss ich mich bei den t\u00e4glichen Klog\u00e4ngen nicht mehr verrenken, und bin noch immer fasziniert, dass die Wasserzufuhr von ganz alleine stoppt. (Ja, ich bleibe immer noch stehen und warte, um wirklich sicher sein zu k\u00f6nnen, dass das Wasser wirklich nicht ungewollt ins WC-Becken abflie\u00dft.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbrigens: Seit Tagen klappert die Waschmaschine. Es klingt, als wenn sie sich nach und nach selbst in ihre Einzelteile zerlegen w\u00fcrde. Ich sag&#8216; ja nur. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>oder wie schnell man in Schablonen ger\u00e4t. Aber eigentlich ist es einfach so, dass mir gerade langweilig ist. Deswegen kommt selbst ein Blogeintrag \u00fcber den nach 8 Jahren Undicht-Seins ausgetauschten Sp\u00fclkasten gerade gelegen. Der Sp\u00fclkasten ist also seit dem legend\u00e4ren &hellip; <a href=\"https:\/\/sajec.de\/blog\/die-erhabenheit-eines-funktionierenden-spuelkastens\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19281","post","type-post","status-publish","format-standard","hentry","category-tagebuch"],"_links":{"self":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/comments?post=19281"}],"version-history":[{"count":2,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19281\/revisions"}],"predecessor-version":[{"id":19283,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/posts\/19281\/revisions\/19283"}],"wp:attachment":[{"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/media?parent=19281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/categories?post=19281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sajec.de\/blog\/wp-json\/wp\/v2\/tags?post=19281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}